{"id":1388,"date":"2017-03-28T08:03:49","date_gmt":"2017-03-28T08:03:49","guid":{"rendered":"http:\/\/www.figueruelas.es\/?page_id=1388"},"modified":"2021-03-08T10:50:09","modified_gmt":"2021-03-08T09:50:09","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br><\/p><h2>1. Introducci\u00f3n<\/h2><p>Nuestra web, <a href=\"https:\/\/www.figueruelas.es\">https:\/\/www.figueruelas.es<\/a> (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies tambi\u00e9n son colocadas por terceros a los que hemos contratado. En el siguiente documento te informamos sobre el uso de cookies en nuestra web.<\/p><h2>2. \u00bfQu\u00e9 son las cookies?<\/h2><p>Una cookie es un peque\u00f1o archivo que se env\u00eda junto con las p\u00e1ginas de esta web y que tu navegador almacena en el disco duro de su ordenador u otro dispositivo. La informaci\u00f3n almacenada puede ser devuelta a nuestros servidores o a los servidores de terceros apropiados durante una visita posterior.<\/p><h2>3. \u00bfQu\u00e9 son los scripts?<\/h2><p>Un script es un fragmento de c\u00f3digo de programa que se utiliza para hacer que nuestra web funcione correctamente y de forma interactiva. Este c\u00f3digo se ejecuta en nuestro servidor o en tu dispositivo.<\/p><h2>4. \u00bfQu\u00e9 es una baliza web?<\/h2><p>Una baliza web (o una etiqueta de p\u00edxel) es una peque\u00f1a e invisible pieza de texto o imagen en una web que se utiliza para monitorear el tr\u00e1fico en una web. Para ello, se almacenan varios datos sobre usted mediante estas balizas web.<\/p><h2>5. Cookies<\/h2><h3>5.1 Cookies t\u00e9cnicas o funcionales<\/h3><p>Algunas cookies aseguran que ciertas partes de la web funcionen correctamente y que tus preferencias de usuario sigan record\u00e1ndose. Al colocar cookies funcionales, te facilitamos la visita a nuestra web. De esta manera, no necesitas introducir repetidamente la misma informaci\u00f3n cuando visitas nuestra web y, por ejemplo, los art\u00edculos permanecen en tu cesta de la compra hasta que hayas pagado. Podemos colocar estas cookies sin tu consentimiento.<\/p><h3>5.2 Cookies de marketing\/seguimiento<\/h3><p>Las cookies de marketing\/seguimiento son cookies, o cualquier otra forma de almacenamiento local, usadas para crear perfiles de usuario para mostrar publicidad o para hacer el seguimiento del usuario en esta web o en varias webs con fines de marketing similares.<\/p><h3>5.3 Redes sociales<\/h3><p>En nuestra web hemos incluido contenido de Instagram para promover p\u00e1ginas web (p.ej.: \u00abMe gusta\u00bb, \u00abPinear\u00bb) o compartir (p.ej.: \u00abtuitear\u00bb) en redes sociales como Instagram. Este contenido est\u00e1 incrustado con c\u00f3digo derivado de Instagram y guarda cookies. Este contenido podr\u00eda procesar cierta informaci\u00f3n para anuncios personalizados.<\/p><p>Por favor lea la pol\u00edtica de privacidad de estas redes sociales (que puede cambiar frecuentemente) para saber que hacen con sus datos (personales) que procesan usando estas cookies. Los datos que reciben son anonimizados lo m\u00e1ximo posible. Instagram est\u00e1 ubicado en los Estados Unidos.<\/p><h2>6. Cookies usadas<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service \" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WordPress para desarrollo de sitios web.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service \" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Complianz para gesti\u00f3n del consentimiento de cookies.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.&nbsp;Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">pol\u00edtica de privacidad de Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar la ID de la pol\u00edtica de cookies aceptada<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar preferencias de consentimiento de cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store if the cookie banner has been dismissed<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service \" data-service=\"google-fonts\" data-category=\"marketing\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Fonts para mostrar fuentes web.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">nada<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Solicitar la direcci\u00f3n IP del usuario<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service \" data-service=\"google-maps\" data-category=\"marketing\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Maps para mostrar mapas.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">pol\u00edtica de privacidad de Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">nada<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Solicitar la direcci\u00f3n IP del usuario<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varios<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varios\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varios\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">FUTURE_ACTION_CALENDAR_IS_VISIBLE_classic-editor<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">__Secure-YNID<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">__Secure-ROLLOUT_TOKEN<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">__Secure-YEC<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_INFO1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_PRIVACY_METADATA<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">TESTCOOKIESENABLED<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimiento<\/h2><p>Cuando visites nuestra web por primera vez, te mostraremos una ventana emergente con una explicaci\u00f3n sobre las cookies. Tan pronto como hagas clic en \u00abGuardar preferencias\u00bb, aceptas que usemos las categor\u00edas de cookies y plugins que has seleccionado en la ventana emergente, tal y como se describe en esta pol\u00edtica de cookies. Puedes desactivar el uso de cookies a trav\u00e9s de tu navegador, pero, por favor, ten en cuenta que nuestra web puede dejar de funcionar correctamente.<\/p><h3>7.1 Gestiona tus ajustes de consentimiento<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Has cargado la pol\u00edtica de cookies sin compatibilidad con JavaScript.&nbsp;En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3n\/desactivaci\u00f3n y borrado de cookies<\/h2><p>Puedes utilizar tu navegador de Internet para eliminar las cookies de forma autom\u00e1tica o manual. Tambi\u00e9n puedes especificar que ciertas cookies no pueden ser colocadas. Otra opci\u00f3n es cambiar los ajustes de tu navegador de Internet para que recibas un mensaje cada vez que se coloca una cookie. Para obtener m\u00e1s informaci\u00f3n sobre estas opciones, consulta las instrucciones de la secci\u00f3n \u00abAyuda\u00bb de tu navegador.<\/p><p>Ten en cuenta que nuestra web puede no funcionar correctamente si todas las cookies est\u00e1n desactivadas. Si borras las cookies de tu navegador, se volver\u00e1n a colocar despu\u00e9s de tu consentimiento cuando vuelvas a visitar nuestras webs.<\/p><h2>9. Tus derechos con respecto a los datos personales<\/h2><p>Tienes los siguientes derechos con respecto a tus datos personales:<\/p><ul>\n                    <li>Tiene derecho a saber por qu\u00e9 se necesitan tus datos personales, qu\u00e9 suceder\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                    <li>Derecho de acceso: tienes derecho a acceder a tus datos personales que conocemos.<\/li>\n                    <li>Derecho de rectificaci\u00f3n: tienes derecho a completar, rectificar, borrar o bloquear tus datos personales cuando lo desees.<\/li>\n                    <li>Si nos das tu consentimiento para procesar tus datos, tienes derecho a revocar dicho consentimiento y a que se eliminen tus datos personales.<\/li>\n                    <li>Derecho de cesi\u00f3n de tus datos: tienes derecho a solicitar todos tus datos personales al responsable del tratamiento y a transferirlos \u00edntegramente a otro responsable del tratamiento.<\/li>\n                    <li>Derecho de oposici\u00f3n: puedes oponerte al tratamiento de tus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el procesamiento.<\/li>\n                <\/ul><p>Para ejercer estos derechos, por favor, contacta con nosotros. Por favor, consulta los detalles de contacto en la parte inferior de esta pol\u00edtica de cookies. Si tienes alguna queja sobre c\u00f3mo gestionamos tus datos, nos gustar\u00eda que nos la hicieras saber, pero tambi\u00e9n tienes derecho a enviar una queja a la autoridad supervisora (la autoridad de protecci\u00f3n de datos).<\/p><h2>10. Datos de contacto<\/h2><p>Para preguntas y\/o comentarios sobre nuestra pol\u00edtica de cookies y esta declaraci\u00f3n, por favor, contacta con nosotros usando los siguientes datos de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">Ayuntamiento de Figueruelas<\/span><br>\n                      <span class=\"cmplz-contact-address\">Avda. Zaragoza , 11 - CP 50639 Figueruelas (Zaragoza)<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espa\u00f1a<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Web: <a href=\"https:\/\/www.figueruelas.es\">https:\/\/www.figueruelas.es<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Correo electr\u00f3nico: <span class=\"cmplz-obfuscate\">&#105;&#110;f&#111;@<span class=\"cmplz-fmail-domain\">e&#120;.co&#109;<\/span>&#102;&#105;&#103;ueru&#101;las&#046;es<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">N\u00famero de tel\u00e9fono: 976 656 002<\/span><\/p><p>Esta pol\u00edtica de cookies se ha sincronizado con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el 30 julio, 2026.<\/p><\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1388","page","type-page","status-publish","hentry","description-off"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Figueruelas - El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"554\" \/>\n\t\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-03-28T08:03:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-08T09:50:09+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.figueruelas.es#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.figueruelas.es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#listItem\",\"name\":\"Pol\\u00edtica de cookies\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de cookies\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.figueruelas.es#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/#organization\",\"name\":\"figueruelas.es\",\"description\":\"El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.\",\"url\":\"https:\\\/\\\/www.figueruelas.es\\\/\",\"email\":\"info@figueruelas.es\",\"telephone\":\"+34976656002\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.figueruelas.es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-negro.webp\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#organizationLogo\",\"width\":400,\"height\":120,\"caption\":\"Ayuntamiento de Figueruelas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#webpage\",\"url\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/\",\"name\":\"Pol\\u00edtica de cookies - Ayuntamiento de Figueruelas\",\"description\":\"Esta pol\\u00edtica de cookies fue actualizada por \\u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\\u00f3mico Europeo y Suiza. 1. Introducci\\u00f3n Nuestra web, https:\\\/\\\/www.figueruelas.es (en adelante: \\u00abla web\\u00bb) utiliza cookies y otras tecnolog\\u00edas relacionadas (para mayor comodidad, todas las tecnolog\\u00edas se denominan \\u00abcookies\\u00bb). Las cookies\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/index.php\\\/politica-de-cookies\\\/#breadcrumblist\"},\"datePublished\":\"2017-03-28T08:03:49+01:00\",\"dateModified\":\"2021-03-08T10:50:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/#website\",\"url\":\"https:\\\/\\\/www.figueruelas.es\\\/\",\"name\":\"Ayuntamiento de Figueruelas\",\"alternateName\":\"Ayuntamiento de Figueruelas\",\"description\":\"El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.figueruelas.es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas","description":"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies","canonical_url":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.figueruelas.es#listItem","position":1,"name":"Inicio","item":"https:\/\/www.figueruelas.es","nextItem":{"@type":"ListItem","@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#listItem","name":"Pol\u00edtica de cookies"}},{"@type":"ListItem","@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#listItem","position":2,"name":"Pol\u00edtica de cookies","previousItem":{"@type":"ListItem","@id":"https:\/\/www.figueruelas.es#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/www.figueruelas.es\/#organization","name":"figueruelas.es","description":"El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.","url":"https:\/\/www.figueruelas.es\/","email":"info@figueruelas.es","telephone":"+34976656002","logo":{"@type":"ImageObject","url":"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2026\/04\/logo-negro.webp","@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#organizationLogo","width":400,"height":120,"caption":"Ayuntamiento de Figueruelas"},"image":{"@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#webpage","url":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/","name":"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas","description":"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.figueruelas.es\/#website"},"breadcrumb":{"@id":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/#breadcrumblist"},"datePublished":"2017-03-28T08:03:49+01:00","dateModified":"2021-03-08T10:50:09+01:00"},{"@type":"WebSite","@id":"https:\/\/www.figueruelas.es\/#website","url":"https:\/\/www.figueruelas.es\/","name":"Ayuntamiento de Figueruelas","alternateName":"Ayuntamiento de Figueruelas","description":"El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.figueruelas.es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Figueruelas - El objetivo principal del portal del Ayuntamiento de Figueruelas es hacer de nuestro ayuntamiento un lugar transparente y accesible a todos.","og:type":"article","og:title":"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas","og:description":"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies","og:url":"https:\/\/www.figueruelas.es\/index.php\/politica-de-cookies\/","og:image":"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg","og:image:secure_url":"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg","og:image:width":554,"og:image:height":636,"article:published_time":"2017-03-28T08:03:49+00:00","article:modified_time":"2021-03-08T09:50:09+00:00","twitter:card":"summary","twitter:title":"Pol\u00edtica de cookies - Ayuntamiento de Figueruelas","twitter:description":"Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el 30 julio, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza. 1. Introducci\u00f3n Nuestra web, https:\/\/www.figueruelas.es (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies","twitter:image":"https:\/\/www.figueruelas.es\/wp-content\/uploads\/2021\/03\/EscudoFigueruelas.jpg"},"aioseo_meta_data":{"post_id":"1388","title":null,"description":null,"keywords":[],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\\\"article\\\":{\\\"articleType\\\":\\\"BlogPosting\\\"},\\\"course\\\":{\\\"name\\\":\\\"\\\",\\\"description\\\":\\\"\\\",\\\"provider\\\":\\\"\\\"},\\\"faq\\\":{\\\"pages\\\":[]},\\\"product\\\":{\\\"reviews\\\":[]},\\\"recipe\\\":{\\\"ingredients\\\":[],\\\"instructions\\\":[],\\\"keywords\\\":[]},\\\"software\\\":{\\\"reviews\\\":[],\\\"operatingSystems\\\":[]},\\\"webPage\\\":{\\\"webPageType\\\":\\\"WebPage\\\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-22 09:00:05","updated":"2025-06-15 18:57:22","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:20:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/pages\/1388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/comments?post=1388"}],"version-history":[{"count":6,"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/pages\/1388\/revisions"}],"predecessor-version":[{"id":2592,"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/pages\/1388\/revisions\/2592"}],"wp:attachment":[{"href":"https:\/\/www.figueruelas.es\/index.php\/wp-json\/wp\/v2\/media?parent=1388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}